{"id":391,"date":"2012-05-14T18:18:43","date_gmt":"2012-05-14T18:18:43","guid":{"rendered":"https:\/\/www.lern-online.net\/blog\/?p=391"},"modified":"2018-06-11T11:50:56","modified_gmt":"2018-06-11T10:50:56","slug":"musikinstrument-im-selbststudium-lernen","status":"publish","type":"post","link":"https:\/\/lern-online.net\/blog\/musikinstrument-im-selbststudium-lernen\/","title":{"rendered":"Musikinstrument im Selbststudium lernen"},"content":{"rendered":"<p>Als jemand, der die Castings-Shows im Fernsehen nicht verfolgt, war ich \u00fcberrascht, als ich letzte Woche in einer Reportage eines \u00f6ffentlich-rechtlichen Senders erfuhr, wie viele es eigentlich so gibt bzw. gab. Es scheint, als h\u00e4tte jeder Sender mindestens eine dieser Shows. In dem Beitrag ging es \u00fcber Teilnehmer und deren Leben nach der Show.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"Bild einer Akustikgitarre\" src=\"http:\/\/www.newmusicacademy.de\/fileadmin\/templates\/applelike_slider\/03.png\" width=\"111\" height=\"140\" \/>Darunter war eine junge Frau, die f\u00fcr ihren Traum ihre Ausbildung aufgab. Heute arbeitet sie in der W\u00e4scherei ihrer Eltern, ohne Aussicht auf eine weitere musikalische Karriere. Deutlich anders erging es einem Viertplatzierten einer bekannten Show. Er spielt Gitarre, komponiert Lieder und tritt ab und zu noch vor Publikum auf. Wenn es sein muss auch spontan und ohne Bezahlung in der Fu\u00dfg\u00e4ngerzone. Seine Akustikgitarre ist immer dabei.<\/p>\n<p>Jugendliche, die sich diese Shows ansehen, tr\u00e4umen auch von der gro\u00dfen Karriere auf der Showb\u00fchne. Das dahinter harte Arbeit steckt, erkenne sie jedoch im ersten Blick nicht. Ich pers\u00f6nlich bin der Meinung, dass jeder der hoch hinaus will, erst klein anfangen muss. Das kann im Fall eines Musikers erst mit dem Erlernen eines Musikinstruments beginnen. Wer sich nicht zum Pauken von Noten und \u00dcben eines Instruments zwingen und nur Lieder nachsingen m\u00f6chte, dem kann ich nur sagen, dass nur wenige die Stimme hierf\u00fcr mitbringen.<\/p>\n<p>Nun ist das Erlernen eines Musikinstruments nicht so einfach und oftmals sehr kostspielig. Hat man einen Lehrer gefunden, hat dieser oft einen engen Zeitplan, die \u00dcbungsabst\u00e4nde sind gro\u00df oder die Fortschritte zu langsam. Wer dennoch wie der Kandidat oben das Spielen einer Gitarre erlernen m\u00f6chte, jedoch mit den obigen Problemen zu k\u00e4mpfen hat, dem bietet die newmusic academy \u201cGitarre selber lernen\u201c-Kurse an.<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_86 counter-flat ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">INHALTSVERZEICHNIS<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a985e209fa34\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a985e209fa34\"  aria-label=\"Toggle\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/lern-online.net\/blog\/musikinstrument-im-selbststudium-lernen\/#Gitarre_spielen_lernen_mit_Videos\" >Gitarre spielen lernen mit Videos<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/lern-online.net\/blog\/musikinstrument-im-selbststudium-lernen\/#Preis_Kuendigung\" >Preis &amp; K\u00fcndigung<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/lern-online.net\/blog\/musikinstrument-im-selbststudium-lernen\/#Fazit\" >Fazit<\/a><\/li><\/ul><\/nav><\/div>\n<h3><span class=\"ez-toc-section\" id=\"Gitarre_spielen_lernen_mit_Videos\"><\/span>Gitarre spielen lernen mit Videos<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Ich habe mir die Seite newmusicacademy.de einmal genauer angesehen. Das Ganze funktioniert wie folgt:<\/p>\n<ul>\n<li>Zuerst entscheidet man sich f\u00fcr ein Instrument (Rock- oder Akustikgitarre)<\/li>\n<li>Dann w\u00e4hlt man sich ein Startlevel aus. Jedes Level besteht aus 3 Abschnitten. Jeder Abschnitt dauert 2 Monate (1 Level = 6 Monate)<\/li>\n<li>In jedem Abschnitt (alle 2 Monate) bekommt man ein Lehrbuch, 2 DVDs und Jamtrack CDs zugesandt. Mithilfe dieser beginnt man mit dem Selbststudium<\/li>\n<li>Jedem Sch\u00fcler steht ein Fernlehrer zur Verf\u00fcgung, der bei Problemen zur Seite steht. Diesem kann man auch Audio- oder Videoaufnahmen zur Analyse\/Kontrolle zusenden.<\/li>\n<\/ul>\n<h3><span class=\"ez-toc-section\" id=\"Preis_Kuendigung\"><\/span>Preis &amp; K\u00fcndigung<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Der 1. Abschnitt (2 Monate) kostet 75 \u00e2\u201a\u00ac zzgl. 4,95 \u00e2\u201a\u00ac f\u00fcr den Versand innerhalb der Bundesrepublik. Hiernach bezahlt man 75 \u00e2\u201a\u00ac f\u00fcr jeden Monat , d.h. der 2. Abschnitt kostet 150 \u00e2\u201a\u00ac (+ Versandkosten), der dritte ebenfalls. 6 Monate Gitarrenuntericht kostet somit insgesamt\u00a0<strong>389,85 \u00e2\u201a\u00ac<\/strong>.<\/p>\n<p>Wer doch das Gef\u00fchl hat, dass er mit dem\u00a0<a title=\"Videos zum Gittare spielen lernen\" href=\"http:\/\/www.newmusicacademy.de\/learninghome\/instrumente\/gitarre-lernen\/\" target=\"_blank\" rel=\"noopener\">Gitarre lernen Video<\/a>\u00a0nicht zurecht kommt und doch Klavier oder Drums spielen lernen m\u00f6chte (ist dort auch m\u00f6glich), der muss sp\u00e4testens 4 Wochen vor dem n\u00e4chsten Abschnitt k\u00fcndigen. Sonst werden die neuen Unterrichtsmaterialien zugeschickt.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Fazit\"><\/span>Fazit<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Insgesamt macht das Angebot einen sehr guten Eindruck. Unentschlossenen bietet die Seite Gratis-Lektionen an. Jeder Teilnehmer kann zudem ein Diplom erhalten und \u2013 falls gew\u00fcnscht \u2013 eine Pr\u00fcfung ablegen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Als jemand, der die Castings-Shows im Fernsehen nicht verfolgt, war ich \u00fcberrascht, als ich letzte Woche in einer Reportage eines \u00f6ffentlich-rechtlichen Senders erfuhr, wie viele es eigentlich so gibt bzw. gab. Es scheint, als h\u00e4tte jeder Sender mindestens eine dieser Shows. In dem Beitrag ging es \u00fcber Teilnehmer und deren&#8230; <a href=\"https:\/\/lern-online.net\/blog\/musikinstrument-im-selbststudium-lernen\/\">Read more &raquo;<\/a><\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[31],"tags":[133,772,451],"class_list":["post-391","post","type-post","status-publish","format-standard","hentry","category-kultur","tag-instrument","tag-musik","tag-selbststudium"],"_links":{"self":[{"href":"https:\/\/lern-online.net\/blog\/wp-json\/wp\/v2\/posts\/391","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lern-online.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lern-online.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lern-online.net\/blog\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/lern-online.net\/blog\/wp-json\/wp\/v2\/comments?post=391"}],"version-history":[{"count":0,"href":"https:\/\/lern-online.net\/blog\/wp-json\/wp\/v2\/posts\/391\/revisions"}],"wp:attachment":[{"href":"https:\/\/lern-online.net\/blog\/wp-json\/wp\/v2\/media?parent=391"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lern-online.net\/blog\/wp-json\/wp\/v2\/categories?post=391"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lern-online.net\/blog\/wp-json\/wp\/v2\/tags?post=391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}