{"id":4572,"date":"2018-12-17T19:13:21","date_gmt":"2018-12-17T18:13:21","guid":{"rendered":"https:\/\/www.lern-online.net\/blog\/?p=4572"},"modified":"2018-12-17T19:13:21","modified_gmt":"2018-12-17T18:13:21","slug":"lernen-mit-blogs-auf-praxiswissen-von-profis-zurueckgreifen","status":"publish","type":"post","link":"https:\/\/lern-online.net\/blog\/lernen-mit-blogs-auf-praxiswissen-von-profis-zurueckgreifen\/","title":{"rendered":"Lernen mit Blogs &#8211; auf Praxiswissen von Profis zur\u00fcckgreifen"},"content":{"rendered":"<p>Im Internet gibt es mittlerweile fast so viele Blogs wie Sand am Meer. Viele davon sind inhaltlich in einer sehr hohen Qualit\u00e4t und bieten Informationen mit einem Mehrwert. Im Vergleich zu den statischen und theoretischen Informationen, die B\u00fccher h\u00e4ufig bieten, haben Blogs den Vorteil, dass dahinter Verfasser stehen, die sich mit den Themen in der Praxis befassen. Genau hier liegt der Grund, warum Blogs eine sinnvolle Erg\u00e4nzung beim Lernen sind, denn sie k\u00f6nnen viel praktische Erfahrung bieten, die theoretische Informationen klarer erscheinen lassen.<\/p>\n<p><!--more--><\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_86 counter-flat ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">INHALTSVERZEICHNIS<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a984b1a99d45\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a984b1a99d45\"  aria-label=\"Toggle\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/lern-online.net\/blog\/lernen-mit-blogs-auf-praxiswissen-von-profis-zurueckgreifen\/#Inhalte_aus_der_Praxis\" >Inhalte aus der Praxis<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/lern-online.net\/blog\/lernen-mit-blogs-auf-praxiswissen-von-profis-zurueckgreifen\/#Selbst_organisiertes_Lernen\" >Selbst organisiertes Lernen<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/lern-online.net\/blog\/lernen-mit-blogs-auf-praxiswissen-von-profis-zurueckgreifen\/#Kurze_Lernphasen_als_idealer_Themeneinstieg\" >Kurze Lernphasen als idealer Themeneinstieg<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/lern-online.net\/blog\/lernen-mit-blogs-auf-praxiswissen-von-profis-zurueckgreifen\/#Blogs_als_Begleitung_fuer_den_Unterricht\" >Blogs als Begleitung f\u00fcr den Unterricht<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Inhalte_aus_der_Praxis\"><\/span>Inhalte aus der Praxis<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Wer im Internet selbst einen Lernblog betreibt und gefunden werden will, sollte nicht einfach nur seine Themen ver\u00f6ffentlichen, sondern seine Inhalte auch nach SEO Richtlinien gestalten. <a href=\"https:\/\/lern-online.net\/blog\/2018\/11\/15\/suchmaschinenoptimierung-seo-analyse-optimierung\/\">Tipps<\/a>, wie man sp\u00e4ter seinen eigenen Blog optimieren kann, gibt es beispielsweise in einem <a href=\"https:\/\/www.seo-galaxy.com\/blog\/\" target=\"_blank\" rel=\"noopener\">SEO Blog<\/a>. So wird die Ver\u00f6ffentlichung eines Blogs nicht nur zum Hobby, sondern die Inhalte, die einen starken Bezug zur Praxis haben, werden auch von vielen Menschen gefunden. Vor allem von diesem praxisnahen Wissen kann beim Lernen mit Blogs profitiert werden.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Selbst_organisiertes_Lernen\"><\/span>Selbst organisiertes Lernen<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Das Arbeiten mit Blogs hat viele Vorteile, vor allem lernen viele auch das Lernen mit Blogs. Die Verwendung von Blogs als Informationsquelle fordert unter anderem ein hohes Ma\u00df an Selbstorganisation. Dazu geh\u00f6rt beispielsweise die Suche nach qualitativ hochwertigen Blogs mit relevanten Themen, die auch in einer brauchbaren Form aufgearbeitet werden. Wer mit Blogs lernt, der muss auch selbstst\u00e4ndig immer wieder kontrollieren, ob neue Inhalte ver\u00f6ffentlicht wurden und, ob diese auch zum aktuellen Themenschwerpunkt passen. Wer einen besonders gro\u00dfen Nutzen aus den Blogs ziehen will, der kann auch in Kontakt mit den Erstellern der Blogs treten. Dies erfordert nat\u00fcrlich zus\u00e4tzliche Arbeit, vor allem wenn im privaten Gespr\u00e4ch Fragen gekl\u00e4rt werden zu einem Thema.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Kurze_Lernphasen_als_idealer_Themeneinstieg\"><\/span>Kurze Lernphasen als idealer Themeneinstieg<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Im Vergleich zu den fast endlosen Seiten, auf denen in manchen B\u00fcchern vor allem schwierige Themen behandelt werden, haben die Ersteller von Blogs die F\u00e4higkeit, solche harten Brocken in kleine H\u00e4ppchen aufzuteilen, die dann ersch\u00f6pfend behandelt werden. Die Aufteilung in kleinere Abschnitte macht durchaus Sinn, da damit ein gr\u00f6\u00dferer <a href=\"https:\/\/lern-online.net\/blog\/2018\/07\/26\/vokabeln-einfacher-lernen-3-tipps-um-vokabeln-schneller-und-einfacher-zu-lernen\/\">Lernerfolg<\/a> erzielt werden kann. Das Gehirn ist einer andauernden Belastung auch nicht gewachsen und erm\u00fcdet ebenfalls. Daher gilt bei jedem Lernen sich den Stoff in kleine Abschnitte zu unterteilen. Hier haben Blogs in jedem Fall einen Vorteil, da sie ein Thema im Kern in geringem Umfang behandeln. Sie sind damit ein idealer Einstieg in eine Thematik und, nach dem ein Abschnitt erarbeitet wurde, kann man zum n\u00e4chsten Abschnitt \u00fcbergehen und sich in die Materie vertiefen.<\/p>\n<div id=\"attachment_4575\" style=\"width: 650px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/lern-online.net\/blog\/wp-content\/blog-steine.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-4575\" class=\"size-full wp-image-4575\" src=\"https:\/\/lern-online.net\/blog\/wp-content\/blog-steine.jpg\" alt=\"\" width=\"640\" height=\"426\" srcset=\"https:\/\/lern-online.net\/blog\/wp-content\/blog-steine.jpg 640w, https:\/\/lern-online.net\/blog\/wp-content\/blog-steine-300x200.jpg 300w, https:\/\/lern-online.net\/blog\/wp-content\/blog-steine-624x415.jpg 624w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><p id=\"caption-attachment-4575\" class=\"wp-caption-text\">Bildquelle: Pixabay User: Wokandapix<\/p><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Blogs_als_Begleitung_fuer_den_Unterricht\"><\/span>Blogs als Begleitung f\u00fcr den Unterricht<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Blogs haben nicht nur einen Nutzen beim Lernen, wenn man bereits welche mit gef\u00fcllten Inhalten nutzt, sondern wenn man sie selbst mit Inhalten bef\u00fcllt. Im Unterricht werden Blogs deshalb immer beliebter, weil sie eine ideale M\u00f6glichkeit sind, f\u00fcr die Sch\u00fcler ein Themengebiet in einer modernen Form aufzuarbeiten. Anstatt langweiliger Plakate ist nun das Internet eine digitale Plakatwand, die dynamisch mit Informationen bef\u00fcllt werden kann. Ein Lernblog kann die Sch\u00fcler von der ersten bis zur letzten Klasse begleiten.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Im Internet gibt es mittlerweile fast so viele Blogs wie Sand am Meer. Viele davon sind inhaltlich in einer sehr hohen Qualit\u00e4t und bieten Informationen mit einem Mehrwert. Im Vergleich zu den statischen und theoretischen Informationen, die B\u00fccher h\u00e4ufig bieten, haben Blogs den Vorteil, dass dahinter Verfasser stehen, die sich&#8230; <a href=\"https:\/\/lern-online.net\/blog\/lernen-mit-blogs-auf-praxiswissen-von-profis-zurueckgreifen\/\">Read more &raquo;<\/a><\/p>\n","protected":false},"author":18,"featured_media":4575,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29,14],"tags":[],"class_list":["post-4572","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-e-learning","category-lernen"],"_links":{"self":[{"href":"https:\/\/lern-online.net\/blog\/wp-json\/wp\/v2\/posts\/4572","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lern-online.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lern-online.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lern-online.net\/blog\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/lern-online.net\/blog\/wp-json\/wp\/v2\/comments?post=4572"}],"version-history":[{"count":3,"href":"https:\/\/lern-online.net\/blog\/wp-json\/wp\/v2\/posts\/4572\/revisions"}],"predecessor-version":[{"id":4576,"href":"https:\/\/lern-online.net\/blog\/wp-json\/wp\/v2\/posts\/4572\/revisions\/4576"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lern-online.net\/blog\/wp-json\/wp\/v2\/media\/4575"}],"wp:attachment":[{"href":"https:\/\/lern-online.net\/blog\/wp-json\/wp\/v2\/media?parent=4572"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lern-online.net\/blog\/wp-json\/wp\/v2\/categories?post=4572"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lern-online.net\/blog\/wp-json\/wp\/v2\/tags?post=4572"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}