{"id":582,"date":"2012-10-29T10:54:26","date_gmt":"2012-10-29T09:54:26","guid":{"rendered":"https:\/\/www.lern-online.net\/blog\/?p=582"},"modified":"2018-06-11T12:32:22","modified_gmt":"2018-06-11T11:32:22","slug":"was-bedeutet-lebenslanges-lernen","status":"publish","type":"post","link":"https:\/\/lern-online.net\/blog\/was-bedeutet-lebenslanges-lernen\/","title":{"rendered":"Was bedeutet lebenslanges Lernen genau?"},"content":{"rendered":"<p>\u201cLebenslanges Lernen\u201e ist eine Wortkombination, die wie kaum eine andere unsere Zukunft bestimmt. Im Grunde bedeutet Sie nichts anderes wie: Wir sind in einem st\u00e4ndigen Prozess des Lernens und Verbesserns gefangen. Egal ob im Beruf, Ehrenamt oder Hobby, nie wird der Punkt erreicht, an dem gesagt werden kann: \u201cIch kann alles\u201e. Die Welt ist sich st\u00e4ndig am Ver\u00e4ndern und diese Ver\u00e4nderung muss man annehmen. Vor allem im Beruf wird dies deutlich: Ohne Fortbildungen und Qualifikationen ist jeder irgendwann nicht mehr Up-to-Date genug. Selbst der Handwerksmeister lernt im Laufe seiner Arbeit dazu. Dabei macht es keinen Unterschied als Kind in der Schule spielend zu lernen oder als Erwachsener eigene Erfahrungen zu erleben. Alle diese Punkte sind nur Teile dessen, was jeden von uns im Leben ausmachen.<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_86 counter-flat ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">INHALTSVERZEICHNIS<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a985af759ff5\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a985af759ff5\"  aria-label=\"Toggle\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/lern-online.net\/blog\/was-bedeutet-lebenslanges-lernen\/#Die_Schule_legt_den_Grundstein\" >Die Schule legt den Grundstein<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/lern-online.net\/blog\/was-bedeutet-lebenslanges-lernen\/#Lernen_im_Beruf\" >Lernen im Beruf<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Die_Schule_legt_den_Grundstein\"><\/span>Die Schule legt den Grundstein<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Schon im Kindergarten werden die ersten Weichen gestellt. Hier lernt ein Kind die Grundlage um erfolgreich mit der Schule beginnen zu k\u00f6nnen. Denn zu meinen, ein Kind w\u00fcrde im Kindergarten nur spielen, ist falsch. Hier lernen Kinder spielend zu lernen. Ohne diese Vorbereitung w\u00e4ren f\u00fcr viele die ersten Jahre Schule sehr schwer. Denn keine andere Zeit im Leben hat so einen gro\u00dfen Einfluss und wird so wenig gesch\u00e4tzt, wie die Schulzeit. Man eignet sich Wissen an, verbessert seine, wie es so sch\u00f6n hei\u00dft, Sozialkompetenz und erreicht nach 9, 10 oder 12 Jahren einen Abschluss, der in den meisten F\u00e4llen das Leben bis zur Rente entscheidet. Die Ausbildung, das soziale Umfeld und Aufstiegschancen, vieles wird abh\u00e4ngig gemacht von der Schule. Daher ist es wichtig, die Schule als Grundstein f\u00fcr lebenslanges Lernen zu sehen. Denn wer in der Schule schon wenig lernt, der wird im sp\u00e4teren Leben sich nicht sonderlich bem\u00fchen mehr zu lernen.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Lernen_im_Beruf\"><\/span>Lernen im Beruf<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Nach erfolgreichem Schulabschluss bricht keine Zeit zur Erholung an. Da die Grundlagen in der Schule gelernt sein sollten, eignet man sich nun das Expertenwissen an. Eine fertige Ausbildung hei\u00dft, man hat eine bestimmte T\u00e4tigkeit gelernt und beherrscht diese besser als jemand, der sie nicht gelernt hat.<br \/>\nNun liegt es an jedem allein, sein K\u00f6nnen weiter zu verbessern. Wer in\u00a0Job Suchmaschinen\u00a0schaut, sieht deutlich: Ohne Fortbildungen kann niemand viel erreichen. Jede Firma sucht den besten Mann, mit den besten Qualifikationen. Und um sich in diesem Markt behaupten zu k\u00f6nnen, muss man immer und immer weiter lernen. Genau das macht das lebenslange Lernen aus. Nicht f\u00fcr die Firma, nicht f\u00fcr die Lehrer wird gelernt. Am Ende bringen diese F\u00e4higkeiten nur uns selbst etwas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cLebenslanges Lernen\u201e ist eine Wortkombination, die wie kaum eine andere unsere Zukunft bestimmt. Im Grunde bedeutet Sie nichts anderes wie: Wir sind in einem st\u00e4ndigen Prozess des Lernens und Verbesserns gefangen. Egal ob im Beruf, Ehrenamt oder Hobby, nie wird der Punkt erreicht, an dem gesagt werden kann: \u201cIch kann&#8230; <a href=\"https:\/\/lern-online.net\/blog\/was-bedeutet-lebenslanges-lernen\/\">Read more &raquo;<\/a><\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[225,140,223,224,193],"class_list":["post-582","post","type-post","status-publish","format-standard","hentry","category-lernen","tag-beruf","tag-job","tag-labenslang","tag-leben","tag-lernen-2"],"_links":{"self":[{"href":"https:\/\/lern-online.net\/blog\/wp-json\/wp\/v2\/posts\/582","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lern-online.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lern-online.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lern-online.net\/blog\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/lern-online.net\/blog\/wp-json\/wp\/v2\/comments?post=582"}],"version-history":[{"count":0,"href":"https:\/\/lern-online.net\/blog\/wp-json\/wp\/v2\/posts\/582\/revisions"}],"wp:attachment":[{"href":"https:\/\/lern-online.net\/blog\/wp-json\/wp\/v2\/media?parent=582"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lern-online.net\/blog\/wp-json\/wp\/v2\/categories?post=582"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lern-online.net\/blog\/wp-json\/wp\/v2\/tags?post=582"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}